{"id":53824,"date":"2026-05-10T04:00:03","date_gmt":"2026-05-09T21:00:03","guid":{"rendered":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/"},"modified":"2026-05-10T04:00:03","modified_gmt":"2026-05-09T21:00:03","slug":"%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1","status":"publish","type":"post","link":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/","title":{"rendered":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07"},"content":{"rendered":"\n\t\t\t\t\t\t<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"246\" height=\"90\" src=\"https:\/\/traderider.com\/gold\/wp-content\/uploads\/2020\/01\/spdr-logo.png\" alt=\"\" class=\"wp-image-226\"\/><\/figure><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<p>\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR GOLD SHARES \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07<strong>\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/strong>\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49<\/p>\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t<h5 style=\"color:#ffffff;\">\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569<\/h5>\n\t\t\t\t\t\t<div class=\"box-spdr\"><table width=\"100%\" border=\"1\" align=\"center\" cellpadding=\"10\" cellspacing=\"0\">\n\t\t\t\t\t\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t<td>\u0e40\u0e27\u0e25\u0e32<\/td>\n\t\t\t\t\t\t\t\t\t\t<td>\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48<\/td>\n\t\t\t\t\t\t\t\t\t\t<td>\u0e16\u0e37\u0e2d\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 (\u0e15\u0e31\u0e19)<\/td>\n\t\t\t\t\t\t\t\t\t\t<td>\u0e16\u0e37\u0e2d\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 (\u0e15\u0e31\u0e19)<\/td>\n\t\t\t\t\t\t\t\t\t\t<td>Gold spot price (Bid)<\/td>\n\t\t\t\t\t\t\t\t\t\t<td>\u0e02\u0e36\u0e49\u0e19\/\u0e25\u0e07<\/td>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t<td >04:00<\/td>\n\t\t\t\t\t\t\t<td>1<\/td>\n\t\t\t\t\t\t\t<td class=\"normal\">1,034.00<\/td>\n\t\t\t\t\t\t\t<td class=\"normal\">1,034.00<\/td>\n\t\t\t\t\t\t\t<td>4,741.40<\/td>\n\t\t\t\t\t\t\t<td class=\"normal\">0.00<\/td>\n\t\t\t\t\t\t<\/tr><tr><td>\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/td><td colspan=\"5\" class=\"normal\" style=\"text-align:center!important;\"><span id=\"spdr-change\">\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/span><\/td><\/tr><tr><td>\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49<\/td><td colspan=\"5\" class=\"normal\" style=\"text-align:center!important;\"><span id=\"spdr-today-change\">\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/span><\/td><\/tr><\/tbody>\n\t\t\t\t\t\t<\/table><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background has-vivid-red-background-color\" href=\"https:\/\/traderider.com\/gold\/spdr-\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\/\" style=\"border-radius:5px\">\u0e14\u0e39 SPDR \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07<\/a><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<p class=\"wp-block-paragraph\">\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR GOLD SHARES \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01 <strong>\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/strong>\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 1 \u0e13 \u0e40\u0e27\u0e25\u0e32 04:00\u0e19. \u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32 4,741.40 \u0e14\u0e2d\u0e25\u0e25\u0e48\u0e32\u0e2b\u0e4c\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e15\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e0b\u0e4c<br>\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR GOLD SHARES \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 1,034.00 \u0e15\u0e31\u0e19 <\/p>\n\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<p class=\"wp-block-paragraph\">\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07 : SPDR GOLD SHARES \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01<\/p>\n\t\t\t\t\t\t\n\t\t\t\t\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e40\u0e27\u0e25\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e16\u0e37\u0e2d\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 (\u0e15\u0e31\u0e19) \u0e16\u0e37\u0e2d\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 (\u0e15\u0e31\u0e19) Gold spot price (Bid) \u0e02\u0e36\u0e49\u0e19\/\u0e25\u0e07 04:00 1 1,034.00 1,034.00 4,741.40 0.00 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR GOLD SHARES \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 1 \u0e13 \u0e40\u0e27\u0e25\u0e32 04:00\u0e19. \u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32 4,741.40 \u0e14\u0e2d\u0e25\u0e25\u0e48\u0e32\u0e2b\u0e4c\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e15\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e0b\u0e4c\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR GOLD SHARES \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 1,034.00 \u0e15\u0e31\u0e19 \u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07 : SPDR GOLD SHARES \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01<\/p>\n","protected":false},"author":1,"featured_media":671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"gold_price_text":"<strong style=\"line-height: 35px;\">\u0e40\u0e27\u0e25\u0e32 04:00\u0e19. \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/strong>","gold_change_text":"<strong>1,034.00<\/strong> \u0e15\u0e31\u0e19","gold_tang_text":"<strong>$4,741.40\/Onz<\/strong>","gold_today_text":"<span style=\"font-size:18px;\">\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/span>","spdr_time":"04:00","spdr_up_dwn":"","meta_title":"","meta_description":"","keywords":"","footnotes":""},"categories":[17],"tags":[16,239,250,251,240,242,241,248,238,247,253,256,249,255,254,257,260,259,261,252,246,243,262,245,244,263,258],"class_list":["post-53824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spdr","tag-spdr","tag-spdr-gold-trust","tag-spdr-gold-trust-","tag-spdr-gold-","tag-spdr-","tag-spdr--","tag-spdr---","tag-spdr-------","tag--spdr---spdr-gold-trust","tag--spdr----","tag--spdr-","tag--spdr","tag---spdr"],"a3_pvc":{"activated":false,"total_views":127,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 - Traderider<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/traderider.com\/gold\/\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33-spdr-gold-10-\u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21-2569-\u0e44\u0e21\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/#\\\/schema\\\/person\\\/47256ad6b2beae57631d6ed7e25e2ca8\"},\"headline\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\",\"datePublished\":\"2026-05-09T21:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/\"},\"wordCount\":19,\"image\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/traderider.com\\\/gold\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/spdr-no-trade.jpg\",\"keywords\":[\"SPDR\",\"spdr gold trust\",\"spdr gold trust \u0e02\u0e48\u0e32\u0e27\",\"spdr gold \u0e04\u0e37\u0e2d\",\"spdr \u0e01\u0e23\u0e32\u0e1f\",\"spdr \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\",\"spdr \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 \u0e17\u0e2d\u0e07\",\"spdr \u0e02\u0e32\u0e22\",\"spdr \u0e02\u0e32\u0e22\u0e17\u0e2d\u0e07\",\"spdr \u0e02\u0e48\u0e32\u0e27\",\"spdr \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23\",\"spdr \u0e0b\u0e37\u0e49\u0e2d \u0e17\u0e2d\u0e07 \u0e40\u0e1e\u0e34\u0e48\u0e21\",\"spdr \u0e0b\u0e37\u0e49\u0e2d \u0e2b\u0e23\u0e37\u0e2d \u0e02\u0e32\u0e22 \u0e17\u0e2d\u0e07 \u0e23\u0e39\u0e49 \u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\",\"spdr \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\",\"spdr \u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e2d\u0e07\",\"spdr \u0e15\u0e31\u0e19\",\"spdr \u0e16\u0e37\u0e2d \u0e04\u0e23\u0e2d\u0e07\",\"spdr \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32\",\"spdr \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32\",\"spdr\u0e04\u0e37\u0e2d\",\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e04\u0e37\u0e2d \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr gold trust\",\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e16\u0e37\u0e2d \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32 \u0e01\u0e35\u0e48 \u0e15\u0e31\u0e19\",\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32\",\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\",\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32 spdr\",\"\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32 spdr\",\"\u0e15\u0e32\u0e23\u0e32\u0e07 spdr\"],\"articleSection\":[\"SPDR\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/\",\"url\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/\",\"name\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 - Traderider\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/traderider.com\\\/gold\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/spdr-no-trade.jpg\",\"datePublished\":\"2026-05-09T21:00:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/#\\\/schema\\\/person\\\/47256ad6b2beae57631d6ed7e25e2ca8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/traderider.com\\\/gold\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/spdr-no-trade.jpg\",\"contentUrl\":\"https:\\\/\\\/traderider.com\\\/gold\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/spdr-no-trade.jpg\",\"width\":500,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/traderider.com\\\/gold\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/#website\",\"url\":\"https:\\\/\\\/traderider.com\\\/gold\\\/\",\"name\":\"\u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07\u0e04\u0e33 \u2013 Forex \u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49,\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR,\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c Forex\",\"description\":\"\u0e23\u0e27\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c Forex \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17\u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e23\u0e32\u0e04\u0e32\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21 Forex \u0e17\u0e2d\u0e07\u0e04\u0e33\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/traderider.com\\\/gold\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/traderider.com\\\/gold\\\/#\\\/schema\\\/person\\\/47256ad6b2beae57631d6ed7e25e2ca8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e23bc93c86d34cf71bf193aa5294250c7ad39c9496b32dd5880c30c76ff0f0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e23bc93c86d34cf71bf193aa5294250c7ad39c9496b32dd5880c30c76ff0f0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e23bc93c86d34cf71bf193aa5294250c7ad39c9496b32dd5880c30c76ff0f0a?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/traderider.com\\\/gold\\\/author\\\/trdfx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 - Traderider","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/traderider.com\/gold\/\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33-spdr-gold-10-\u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21-2569-\u0e44\u0e21\/","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/#article","isPartOf":{"@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/"},"author":{"name":"admin","@id":"https:\/\/traderider.com\/gold\/#\/schema\/person\/47256ad6b2beae57631d6ed7e25e2ca8"},"headline":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07","datePublished":"2026-05-09T21:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/"},"wordCount":19,"image":{"@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/#primaryimage"},"thumbnailUrl":"https:\/\/traderider.com\/gold\/wp-content\/uploads\/2020\/02\/spdr-no-trade.jpg","keywords":["SPDR","spdr gold trust","spdr gold trust \u0e02\u0e48\u0e32\u0e27","spdr gold \u0e04\u0e37\u0e2d","spdr \u0e01\u0e23\u0e32\u0e1f","spdr \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19","spdr \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 \u0e17\u0e2d\u0e07","spdr \u0e02\u0e32\u0e22","spdr \u0e02\u0e32\u0e22\u0e17\u0e2d\u0e07","spdr \u0e02\u0e48\u0e32\u0e27","spdr \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23","spdr \u0e0b\u0e37\u0e49\u0e2d \u0e17\u0e2d\u0e07 \u0e40\u0e1e\u0e34\u0e48\u0e21","spdr \u0e0b\u0e37\u0e49\u0e2d \u0e2b\u0e23\u0e37\u0e2d \u0e02\u0e32\u0e22 \u0e17\u0e2d\u0e07 \u0e23\u0e39\u0e49 \u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23","spdr \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22","spdr \u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e2d\u0e07","spdr \u0e15\u0e31\u0e19","spdr \u0e16\u0e37\u0e2d \u0e04\u0e23\u0e2d\u0e07","spdr \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32","spdr \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32","spdr\u0e04\u0e37\u0e2d","\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e04\u0e37\u0e2d \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr gold trust","\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e16\u0e37\u0e2d \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32 \u0e01\u0e35\u0e48 \u0e15\u0e31\u0e19","\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32","\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 spdr \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49","\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32 spdr","\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e17\u0e2d\u0e07\u0e04\u0e4d\u0e32 spdr","\u0e15\u0e32\u0e23\u0e32\u0e07 spdr"],"articleSection":["SPDR"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/","url":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/","name":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 - Traderider","isPartOf":{"@id":"https:\/\/traderider.com\/gold\/#website"},"primaryImageOfPage":{"@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/#primaryimage"},"image":{"@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/#primaryimage"},"thumbnailUrl":"https:\/\/traderider.com\/gold\/wp-content\/uploads\/2020\/02\/spdr-no-trade.jpg","datePublished":"2026-05-09T21:00:03+00:00","author":{"@id":"https:\/\/traderider.com\/gold\/#\/schema\/person\/47256ad6b2beae57631d6ed7e25e2ca8"},"breadcrumb":{"@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/#primaryimage","url":"https:\/\/traderider.com\/gold\/wp-content\/uploads\/2020\/02\/spdr-no-trade.jpg","contentUrl":"https:\/\/traderider.com\/gold\/wp-content\/uploads\/2020\/02\/spdr-no-trade.jpg","width":500,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/traderider.com\/gold\/%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%97%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b8%b3-spdr-gold-10-%e0%b8%9e%e0%b8%a4%e0%b8%a9%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b8%a1-2569-%e0%b9%84%e0%b8%a1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/traderider.com\/gold\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33 SPDR Gold 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/traderider.com\/gold\/#website","url":"https:\/\/traderider.com\/gold\/","name":"\u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07\u0e04\u0e33 \u2013 Forex \u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49,\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR,\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c Forex","description":"\u0e23\u0e27\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c Forex \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07 \u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17\u0e23\u0e32\u0e04\u0e32\u0e17\u0e2d\u0e07\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 SPDR \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e23\u0e32\u0e04\u0e32\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21 Forex \u0e17\u0e2d\u0e07\u0e04\u0e33","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/traderider.com\/gold\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/traderider.com\/gold\/#\/schema\/person\/47256ad6b2beae57631d6ed7e25e2ca8","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6e23bc93c86d34cf71bf193aa5294250c7ad39c9496b32dd5880c30c76ff0f0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e23bc93c86d34cf71bf193aa5294250c7ad39c9496b32dd5880c30c76ff0f0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e23bc93c86d34cf71bf193aa5294250c7ad39c9496b32dd5880c30c76ff0f0a?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/traderider.com\/gold\/author\/trdfx\/"}]}},"fimg_url":"https:\/\/traderider.com\/gold\/wp-content\/uploads\/2020\/02\/spdr-no-trade.jpg","gold_price_text":"<strong style=\"line-height: 35px;\">\u0e40\u0e27\u0e25\u0e32 04:00\u0e19. \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/strong>","gold_change_text":"<strong>1,034.00<\/strong> \u0e15\u0e31\u0e19","gold_tang_text":"<strong>$4,741.40\/Onz<\/strong>","gold_today_text":"<span style=\"font-size:18px;\">\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/span>","spdr_time":"04:00","spdr_up_dwn":"","meta_title":"","meta_description":"","keywords":"","_links":{"self":[{"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/posts\/53824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/comments?post=53824"}],"version-history":[{"count":0,"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/posts\/53824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/media\/671"}],"wp:attachment":[{"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/media?parent=53824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/categories?post=53824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/traderider.com\/gold\/wp-json\/wp\/v2\/tags?post=53824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}